{"id":1018,"count":3,"description":"Les br\u00fbleurs et inserts bio sont une solution pratique et \u00e9l\u00e9gante qui vous permet de profiter de la vue d'un vrai feu sans avoir besoin d'installer une chemin\u00e9e. Ils sont faciles \u00e0 installer : ils peuvent \u00eatre plac\u00e9s dans des chemin\u00e9es traditionnelles, sur des meubles ou dans des structures sp\u00e9cialement con\u00e7ues. \r\n\r\nIls peuvent \u00eatre utilis\u00e9s aussi bien dans de nouveaux projets que lors de la modernisation de chemin\u00e9es existantes. Leur design minimaliste et leur flamme efficace cr\u00e9ent une atmosph\u00e8re chaleureuse dans n'importe quelle pi\u00e8ce. \r\n\r\nGr\u00e2ce aux inserts et br\u00fbleurs bio, vous pouvez facilement introduire chaleur et \u00e9l\u00e9gance dans l'int\u00e9rieur, sans avoir besoin de travaux de montage compliqu\u00e9s. C'est une alternative \u00e9cologique et fonctionnelle aux chemin\u00e9es traditionnelles. ","link":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/","name":"Br\u00fbleurs et inserts bio","slug":"bruleurs-et-inserts-bio","taxonomy":"product_cat","parent":1017,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Br\u00fbleurs et inserts bio - aflamo.shop - revendeur aflamo certifi\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Br\u00fbleurs et inserts bio - aflamo.shop - revendeur aflamo certifi\u00e9\" \/>\n<meta property=\"og:description\" content=\"Les br\u00fbleurs et inserts bio sont une solution pratique et \u00e9l\u00e9gante qui vous permet de profiter de la vue d&rsquo;un vrai feu sans avoir besoin d&rsquo;installer une chemin\u00e9e. Ils sont faciles \u00e0 installer : ils peuvent \u00eatre plac\u00e9s dans des chemin\u00e9es traditionnelles, sur des meubles ou dans des structures sp\u00e9cialement con\u00e7ues. Ils peuvent \u00eatre utilis\u00e9s aussi bien dans de nouveaux projets que lors de la modernisation de chemin\u00e9es existantes. Leur design minimaliste et leur flamme efficace cr\u00e9ent une atmosph\u00e8re chaleureuse dans n&rsquo;importe quelle pi\u00e8ce. Gr\u00e2ce aux inserts et br\u00fbleurs bio, vous pouvez facilement introduire chaleur et \u00e9l\u00e9gance dans l&rsquo;int\u00e9rieur, sans avoir besoin de travaux de montage compliqu\u00e9s. C&rsquo;est une alternative \u00e9cologique et fonctionnelle aux chemin\u00e9es traditionnelles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/\" \/>\n<meta property=\"og:site_name\" content=\"aflamo.shop - revendeur aflamo certifi\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/s\\\/foyers-bio\\\/bruleurs-et-inserts-bio\\\/\",\"url\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/s\\\/foyers-bio\\\/bruleurs-et-inserts-bio\\\/\",\"name\":\"Br\u00fbleurs et inserts bio - aflamo.shop - revendeur aflamo certifi\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/s\\\/foyers-bio\\\/bruleurs-et-inserts-bio\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/s\\\/foyers-bio\\\/bruleurs-et-inserts-bio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Br\u00fbleurs et inserts bio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/\",\"name\":\"aflamo.shop - revendeur aflamo certifi\u00e9\",\"description\":\"Kominki elektryczne Aflamo i Emotion Flame z funkcj\u0105 grzania\",\"publisher\":{\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/#organization\",\"name\":\"aflamo.shop - revendeur aflamo certifi\u00e9\",\"url\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aflamo.shop\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo2.1-1-1.svg\",\"contentUrl\":\"https:\\\/\\\/aflamo.shop\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo2.1-1-1.svg\",\"caption\":\"aflamo.shop - revendeur aflamo certifi\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/aflamo.shop\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Br\u00fbleurs et inserts bio - aflamo.shop - revendeur aflamo certifi\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/","og_locale":"fr_FR","og_type":"article","og_title":"Br\u00fbleurs et inserts bio - aflamo.shop - revendeur aflamo certifi\u00e9","og_description":"Les br\u00fbleurs et inserts bio sont une solution pratique et \u00e9l\u00e9gante qui vous permet de profiter de la vue d&rsquo;un vrai feu sans avoir besoin d&rsquo;installer une chemin\u00e9e. Ils sont faciles \u00e0 installer : ils peuvent \u00eatre plac\u00e9s dans des chemin\u00e9es traditionnelles, sur des meubles ou dans des structures sp\u00e9cialement con\u00e7ues. Ils peuvent \u00eatre utilis\u00e9s aussi bien dans de nouveaux projets que lors de la modernisation de chemin\u00e9es existantes. Leur design minimaliste et leur flamme efficace cr\u00e9ent une atmosph\u00e8re chaleureuse dans n&rsquo;importe quelle pi\u00e8ce. Gr\u00e2ce aux inserts et br\u00fbleurs bio, vous pouvez facilement introduire chaleur et \u00e9l\u00e9gance dans l&rsquo;int\u00e9rieur, sans avoir besoin de travaux de montage compliqu\u00e9s. C&rsquo;est une alternative \u00e9cologique et fonctionnelle aux chemin\u00e9es traditionnelles.","og_url":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/","og_site_name":"aflamo.shop - revendeur aflamo certifi\u00e9","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/","url":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/","name":"Br\u00fbleurs et inserts bio - aflamo.shop - revendeur aflamo certifi\u00e9","isPartOf":{"@id":"https:\/\/aflamo.shop\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/aflamo.shop\/fr\/s\/foyers-bio\/bruleurs-et-inserts-bio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/aflamo.shop\/fr\/"},{"@type":"ListItem","position":2,"name":"Br\u00fbleurs et inserts bio"}]},{"@type":"WebSite","@id":"https:\/\/aflamo.shop\/fr\/#website","url":"https:\/\/aflamo.shop\/fr\/","name":"aflamo.shop - revendeur aflamo certifi\u00e9","description":"Kominki elektryczne Aflamo i Emotion Flame z funkcj\u0105 grzania","publisher":{"@id":"https:\/\/aflamo.shop\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aflamo.shop\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aflamo.shop\/fr\/#organization","name":"aflamo.shop - revendeur aflamo certifi\u00e9","url":"https:\/\/aflamo.shop\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aflamo.shop\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/aflamo.shop\/wp-content\/uploads\/2019\/10\/logo2.1-1-1.svg","contentUrl":"https:\/\/aflamo.shop\/wp-content\/uploads\/2019\/10\/logo2.1-1-1.svg","caption":"aflamo.shop - revendeur aflamo certifi\u00e9"},"image":{"@id":"https:\/\/aflamo.shop\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aflamo.shop\/fr\/wp-json\/wp\/v2\/product_cat\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aflamo.shop\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/aflamo.shop\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/aflamo.shop\/fr\/wp-json\/wp\/v2\/product_cat\/1017"}],"wp:post_type":[{"href":"https:\/\/aflamo.shop\/fr\/wp-json\/wp\/v2\/product?product_cat=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}